{"id":22253,"date":"2025-02-02T15:42:53","date_gmt":"2025-02-02T08:42:53","guid":{"rendered":"https:\/\/buulog.com\/?page_id=22253"},"modified":"2026-07-13T15:16:03","modified_gmt":"2026-07-13T08:16:03","slug":"public-relations-news","status":"publish","type":"page","link":"https:\/\/buulog.com\/index.php\/public-relations-news\/","title":{"rendered":"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c"},"content":{"rendered":"\n<p>   <\/p>\n\n\n\n<div class=\"wp-block-file\"><object class=\"wp-block-file__embed\" data=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/07\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48(\u0e2a\u0e21\u0e17\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19).\"><\/object><a id=\"wp-block-file--media-1f4e4eae-2580-4251-bf73-bc884b18ea97\" href=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/07\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25.pdf\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48(\u0e2a\u0e21\u0e17\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19)<\/a><a href=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/07\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-1f4e4eae-2580-4251-bf73-bc884b18ea97\">Download<\/a><\/div>\n\n\n\n<p>   <\/p>\n\n\n\n<div class=\"wp-block-file\"><object class=\"wp-block-file__embed\" data=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/07\/Journal_List_a-z-\u0e2a\u0e23\u0e38\u0e1b\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e2a\u0e23\u0e38\u0e1b\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23.\"><\/object><a id=\"wp-block-file--media-1f4e4eae-2580-4251-bf73-bc884b18ea97\" href=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/07\/Journal_List_a-z-\u0e2a\u0e23\u0e38\u0e1b\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23.pdf\">\u0e2a\u0e23\u0e38\u0e1b\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<\/a><a href=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/07\/Journal_List_a-z-\u0e2a\u0e23\u0e38\u0e1b\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-1f4e4eae-2580-4251-bf73-bc884b18ea97\">Download<\/a><\/div>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"724\" height=\"1024\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/05\/S__78749730-724x1024.jpg\" alt=\"\" class=\"wp-image-24201\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/05\/S__78749730-724x1024.jpg 724w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/05\/S__78749730-212x300.jpg 212w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/05\/S__78749730-768x1086.jpg 768w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/05\/S__78749730.jpg 905w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"724\" height=\"1024\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/04\/S__76840990-724x1024.jpg\" alt=\"\" class=\"wp-image-24154\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/04\/S__76840990-724x1024.jpg 724w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/04\/S__76840990-212x300.jpg 212w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/04\/S__76840990-768x1086.jpg 768w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/04\/S__76840990.jpg 1076w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<p>\ud83d\udce3\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e48\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<br>\u2728\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e48\u0e32\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c (\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c)\u2728<br>\u0e43\u0e19\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 19 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2569 \u0e13 \u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23 \u0e42\u0e14\u0e22 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e01\u0e38\u0e25\u0e18\u0e34\u0e14\u0e32 \u0e17\u0e49\u0e27\u0e21\u0e2a\u0e38\u0e02<br>\ud83d\udccc\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21 https:\/\/shorturl.at\/orz0o<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/03\/645445361_1321100173161022_3383840792502862839_n.jpg\" alt=\"\" class=\"wp-image-24133\" width=\"721\" height=\"1020\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/03\/645445361_1321100173161022_3383840792502862839_n.jpg 509w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/03\/645445361_1321100173161022_3383840792502862839_n-212x300.jpg 212w\" sizes=\"(max-width: 721px) 100vw, 721px\" \/><\/figure>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" height=\"16\" width=\"16\" alt=\"\ud83d\udd0e\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t42\/1\/16\/1f50e.png\">\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/p>\n\n\n\n<p><img decoding=\"async\" loading=\"lazy\" height=\"16\" width=\"16\" alt=\"\ud83d\udce3\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tba\/1\/16\/1f4e3.png\">\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e27\u0e0a.) \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2570<\/p>\n\n\n\n<p>\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25: \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e35\u0e40\u0e14\u0e48\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34, \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22, \u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c, \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e04\u0e34\u0e14\u0e04\u0e49\u0e19<\/p>\n\n\n\n<p>\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a: \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 1 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 \u0e16\u0e36\u0e07 15 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569<\/p>\n\n\n\n<p>\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07: \u0e22\u0e37\u0e48\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c <a href=\"https:\/\/nriis.go.th\/?fbclid=IwZXh0bgNhZW0CMTAAYnJpZBExYTRmejB0MlYyaHFKeElZeHNydGMGYXBwX2lkEDIyMjAzOTE3ODgyMDA4OTIAAR7JhjnYKHyAC2S4fOeK3m3-rhMitsM6hJXmFs0nIAXYnXo09ffYsck35SMhfA_aem_5N1IHAoAuihmveMJ0IJWRA\" rel=\"noreferrer noopener\" target=\"_blank\">https:\/\/nriis.go.th<\/a><\/p>\n\n\n\n<p>\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21: \u0e42\u0e17\u0e23. 02 579 1370-9 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"723\" height=\"1024\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/01\/messageImage_1769484584017-723x1024.jpg\" alt=\"\" class=\"wp-image-24031\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/01\/messageImage_1769484584017-723x1024.jpg 723w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/01\/messageImage_1769484584017-212x300.jpg 212w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/01\/messageImage_1769484584017-768x1087.jpg 768w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/01\/messageImage_1769484584017-1085x1536.jpg 1085w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/01\/messageImage_1769484584017-1447x2048.jpg 1447w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/01\/messageImage_1769484584017-scaled.jpg 1808w\" sizes=\"(max-width: 723px) 100vw, 723px\" \/><\/figure>\n\n\n\n<p>\ud83d\udce3 \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e48\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<br>\ud83c\udf93 MSBE 2026<br>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e41\u0e25\u0e30\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34<br>\u0e14\u0e49\u0e32\u0e19 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e40\u0e28\u0e23\u0e29\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2<br>\ud83d\udccc \u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a \u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22<br>\ud83d\udcc4 \u0e17\u0e31\u0e49\u0e07 \u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29<br>\ud83d\uddd3 \u0e2a\u0e48\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e44\u0e14\u0e49\u0e16\u0e36\u0e07: 8 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569<br>\ud83d\udda5 \u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21: 22 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569 (\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c)<br>\u2728 \u0e40\u0e27\u0e17\u0e35\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a<br>\u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08<br>\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e28\u0e23\u0e29\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<br>\ud83c\udf10 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48<br>\ud83d\udc49 https:\/\/cls.ssru.ac.th\/page\/conference<br>\ud83d\udcce \u0e14\u0e39\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e43\u0e19 Poster \u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/01\/0.jpg\" alt=\"\" class=\"wp-image-24004\" width=\"763\" height=\"836\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2026\/01\/0.jpg 516w, https:\/\/buulog.com\/wp-content\/uploads\/2026\/01\/0-274x300.jpg 274w\" sizes=\"(max-width: 763px) 100vw, 763px\" \/><\/figure>\n\n\n\n<p><br>\ud83d\ude80\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<br>\ud83d\udccc \u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1f\u0e23\u0e35!!! \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e04\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e01\u0e33\u0e41\u0e1e\u0e07\u0e41\u0e2a\u0e19 (\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e10\u0e32\u0e19 TCI) \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 1 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e21.\u0e04.-\u0e40\u0e21.\u0e22.69\n<br>\ud83d\udccc \u0e2a\u0e48\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 :\n<br>https:\/\/so17.tci-thaijo.org\/index.php\/JSSK<br><\/p>\n\n\n\n<p><br>\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<br>\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e40\u0e28\u0e23\u0e29\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c<br>TCI : 2 Social Sciences<br>\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e1b\u0e35\u0e17\u0e35\u0e48 22 \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 1 \u0e21.\u0e04.-\u0e21\u0e34.\u0e22 2569<br>\u2800<br>\u0e2a\u0e32\u0e02\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21<br>\u2800\u2022 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14<br>\u2800\u2022 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23<br>\u2800\u2022 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08<br>\u2800\u2022 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19<br>\u2800\u2022 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23<br>\u2800\u2022 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e19<br>\u2800\u2022 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19<br>\u2800\u2022 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c<br>\u2800\u2022 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23<br>\u0e04\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e40\u0e19\u0e35\u0e22\u0e21\u0e01\u0e32\u0e23\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c (TH,ENG) : 4,000 \u0e1a\u0e32\u0e17<br>\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21 &gt;&gt; https:\/\/so15.tci-thaijo.org\/index.php\/bae<br>\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48<br>02-7916000 \u0e15\u0e48\u0e2d 1042 \u0e04\u0e38\u0e13\u0e41\u0e2b\u0e21\u0e48\u0e21 \u0e2b\u0e23\u0e37\u0e2d<br>095-162-5498 \u0e14\u0e23.\u0e2a\u0e21\u0e34\u0e15\u0e32 \u0e01\u0e25\u0e34\u0e48\u0e19\u0e1e\u0e07\u0e28\u0e4c<br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"724\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/11-1-1024x724.jpg\" alt=\"\" class=\"wp-image-23727\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/11-1-1024x724.jpg 1024w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/11-1-300x212.jpg 300w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/11-1-768x543.jpg 768w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/11-1.jpg 1522w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e02\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08 (\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e19\u0e34\u0e2a\u0e34\u0e15\/\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32) \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 #\u0e2d\u0e1a\u0e23\u0e21\u0e08\u0e23\u0e34\u0e22\u0e18\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e43\u0e19\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 11 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2568 \u0e1c\u0e39\u0e49\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e19\u0e35\u0e22\u0e1a\u0e31\u0e15\u0e23\u0e21\u0e35\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 2 \u0e1b\u0e35<br>\u0e14\u0e39\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 https:\/\/drive.google.com\/\u2026\/1AaHPCRWJgJ7qtlNlk\u2026\/view<br>\u23f0\u0e27\u0e31\u0e19\u0e1e\u0e24\u0e2b\u0e31\u0e2a\u0e1a\u0e14\u0e35\u0e17\u0e35\u0e48 11 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2568 (\u0e2d\u0e1a\u0e23\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c)<br>\ud83d\udcf2\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48 https:\/\/docs.google.com\/\u2026\/1FAIpQLSeAwISs3\u2026\/viewform<br>\ud83d\udcb0\u0e04\u0e48\u0e32\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 222 \u0e1a\u0e32\u0e17<br>\u260e \u0e2a\u0e19\u0e43\u0e08\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e04\u0e38\u0e13\u0e2d\u0e32\u0e23\u0e4c\u0e21 Tel. 080-597-2894<br>\ud83d\udce7E-Mail: alps.irb1@gmail.com<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"724\" height=\"1024\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/12-724x1024.jpg\" alt=\"\" class=\"wp-image-23717\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/12-724x1024.jpg 724w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/12-212x300.jpg 212w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/12-768x1087.jpg 768w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/12-1085x1536.jpg 1085w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/12.jpg 1447w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83c\udfaf\ud83c\udfaf \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 64 \u2728<\/h3>\n\n\n\n<p>\ud83d\udcc5 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 17\u201319 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569<br>\ud83d\udccd \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1a\u0e32\u0e07\u0e40\u0e02\u0e19<br>\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19<br>\ud83d\uddd3 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 \u2013 3 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2568<br>\ud83d\udcb0 \u0e04\u0e48\u0e32\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 2,000 \u0e1a\u0e32\u0e17\/\u0e1c\u0e25\u0e07\u0e32\u0e19<br>\ud83d\udc69\u200d\ud83c\udf93 \u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1f\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1f\u0e23\u0e35<br>\ud83d\udcda \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e41\u0e25\u0e30\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34<br>\ud83c\udf10 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21: annualconference.ku.ac.th<br>\ud83d\udce9 \u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21: KUannualconf@gmail.com<br>\ud83d\udcde \u0e42\u0e17\u0e23. 02-579-5548<br>\u0e17\u0e35\u0e48\u0e21\u0e32 : \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"724\" height=\"1024\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/11-724x1024.jpg\" alt=\"\" class=\"wp-image-23718\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/11-724x1024.jpg 724w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/11-212x300.jpg 212w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/11-768x1086.jpg 768w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/11.jpg 1018w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udccc\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e43\u0e08\u0e2a\u0e48\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22 I \u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e25\u0e07\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1e\u0e32\u0e22\u0e31\u0e1e \u0e1b\u0e35\u0e17\u0e35\u0e48 35 \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 2 (\u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 &#8211; \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2568)<\/h3>\n\n\n\n<p>\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e39\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">https:\/\/so05.tci-thaijo.org\/index.php\/pyu\/about\/submissions<\/h4>\n\n\n\n<ul>\n<li>\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e35\u0e22\u0e19\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e27\u0e48\u0e32 \u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e27\u0e34\u0e08\u0e31\u0e22\u0e43\u0e19\u0e21\u0e38\u0e19\u0e29\u0e22\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e08\u0e32\u0e01\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e43\u0e19\u0e21\u0e38\u0e19\u0e29\u0e22\u0e4c \u0e14\u0e49\u0e32\u0e19\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e21\u0e19\u0e38\u0e29\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e17\u0e35\u0e48 \u0e2d\u0e27 0209.5\/\u0e27 7016)<\/li>\n\n\n\n<li>\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e27\u0e34\u0e08\u0e31\u0e22\u0e43\u0e19\u0e21\u0e38\u0e19\u0e29\u0e22\u0e4c \u0e1c\u0e39\u0e49\u0e40\u0e02\u0e35\u0e22\u0e19\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e23\u0e34\u0e22\u0e18\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e17\u0e33\u0e27\u0e34\u0e08\u0e31\u0e22\u0e43\u0e19\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23<\/li>\n<\/ul>\n\n\n\n<p>\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21<br>\u0e01\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e13\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e27\u0e32\u0e23\u0e04\u0e23\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1e\u0e32\u0e22\u0e31\u0e1e<br>\ud83d\udcde\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c: 053-851478 \u0e15\u0e48\u0e2d 344<br>\ud83d\udc8cE-mail: journal@payap.ac.th<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23 #\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1e\u0e32\u0e22\u0e31\u0e1e #\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1e\u0e32\u0e22\u0e31\u0e1e<\/h4>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"540\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/7.10.68-\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31.jpg\" alt=\"\" class=\"wp-image-23676\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/7.10.68-\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31.jpg 960w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/7.10.68-\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31-300x169.jpg 300w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/7.10.68-\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31-768x432.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83d\udce2 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e27\u0e2a\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 27<\/h3>\n\n\n\n<p>\u25fe \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e2b\u0e31\u0e27\u0e02\u0e49\u0e2d &#8220;\u0e08\u0e23\u0e34\u0e22\u0e18\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 AI : \u0e08\u0e32\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23&#8221;<br>\ud83d\uddd3 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e40\u0e2a\u0e32\u0e23\u0e4c\u0e17\u0e35\u0e48 22 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e35\u0e48 23 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2568<br>\ud83d\udccd \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e04\u0e13\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e27\u0e2a\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25<br>\ud83d\udcbb \u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e39\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e41\u0e25\u0e30\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48: https:\/\/www.western.ac.th\/ , https:\/\/research.western.ac.th \u0e42\u0e14\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1a\u0e31\u0e14\u0e19\u0e35\u0e49\u0e08\u0e19\u0e16\u0e36\u0e07 31 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2568<\/p>\n\n\n\n<p>\u260e \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e27\u0e2a\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e42\u0e17\u0e23. 02 563 5252 \u0e15\u0e48\u0e2d 5017 \u0e2b\u0e23\u0e37\u0e2d E-mail: wturesearch@gmail.com<\/p>\n\n\n\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32 : \u0e40\u0e1e\u0e08 Thammasat University Research Division \u0e01\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e21\u0e18.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"724\" height=\"1024\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/7.10.68-\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34-\u0e01\u0e23\u0e38\u0e07\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e08-724x1024.jpg\" alt=\"\" class=\"wp-image-23678\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/7.10.68-\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34-\u0e01\u0e23\u0e38\u0e07\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e08-724x1024.jpg 724w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/7.10.68-\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34-\u0e01\u0e23\u0e38\u0e07\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e08-212x300.jpg 212w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/7.10.68-\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34-\u0e01\u0e23\u0e38\u0e07\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e08-768x1086.jpg 768w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/7.10.68-\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34-\u0e01\u0e23\u0e38\u0e07\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e08-1086x1536.jpg 1086w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/10\/7.10.68-\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34-\u0e01\u0e23\u0e38\u0e07\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e08.jpg 1448w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\ud83c\udfaf\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34 \u201c\u0e01\u0e23\u0e38\u0e07\u0e40\u0e01\u0e48\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22\u201d \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 8<\/h3>\n\n\n\n<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18 &#8211; 19 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2568<br>\u0e13 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e2d\u0e32\u0e04\u0e32\u0e23 100 \u0e1b\u0e35) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32,<br>Deadline submission: 15 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2568<br>Website: https:\/\/www.aru.ac.th\/arucon\/2025<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-file\"><object class=\"wp-block-file__embed\" data=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/2025-02-20_484-68-\u0e02\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e19\u0e38\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e0a\u0e34\u0e0d\u0e2a.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of 368-68-\u0e02\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e17\u0e38\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c (translational Research Fund) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568.\"><\/object><a id=\"wp-block-file--media-1f4e4eae-2580-4251-bf73-bc884b18ea97\" href=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/2025-02-20_484-68-\u0e02\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e19\u0e38\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e0a\u0e34\u0e0d\u0e2a.pdf\">368-68-\u0e02\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e17\u0e38\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c (translational Research Fund) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e1e.\u0e28. 2568<\/a><a href=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/2025-02-20_484-68-\u0e02\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e19\u0e38\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e0a\u0e34\u0e0d\u0e2a.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-1f4e4eae-2580-4251-bf73-bc884b18ea97\">Download<\/a><\/div>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"724\" height=\"1024\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/S__61653096.jpg\" alt=\"\" class=\"wp-image-22474\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/S__61653096.jpg 724w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/S__61653096-212x300.jpg 212w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-file\"><object class=\"wp-block-file__embed\" data=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/368-68-\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e17\u0e38\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c_compressed.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e02\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e19\u0e38\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e0a\u0e34\u0e0d\u0e2a\u0e48\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23 IJIS.\"><\/object><a id=\"wp-block-file--media-1f4e4eae-2580-4251-bf73-bc884b18ea97\" href=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/368-68-\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e17\u0e38\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c_compressed.pdf\">\u0e02\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e19\u0e38\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e0a\u0e34\u0e0d\u0e2a\u0e48\u0e07\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e43\u0e19\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23 IJIS<\/a><a href=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/368-68-\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e17\u0e38\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c_compressed.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-1f4e4eae-2580-4251-bf73-bc884b18ea97\">Download<\/a><\/div>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-file\"><object class=\"wp-block-file__embed\" data=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/369-68-\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21-\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e43\u0e19\u0e07\u0e32\u0e19-\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08_compressed.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of 369-68-\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e43\u0e19\u0e07\u0e32\u0e19 .\"\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 2568\" (Thailand Research Expo 2025) \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 20 \u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\"><\/object><a id=\"wp-block-file--media-1f4e4eae-2580-4251-bf73-bc884b18ea97\" href=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/369-68-\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21-\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e43\u0e19\u0e07\u0e32\u0e19-\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08_compressed.pdf\">369-68-\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e43\u0e19\u0e07\u0e32\u0e19 &#8220;\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 2568&#8221; (Thailand Research Expo 2025) \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 20 \u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32<\/a><a href=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/369-68-\u0e02\u0e2d\u0e40\u0e0a\u0e34\u0e0d\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21-\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e43\u0e19\u0e07\u0e32\u0e19-\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08_compressed.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-1f4e4eae-2580-4251-bf73-bc884b18ea97\">Download<\/a><\/div>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"724\" height=\"1024\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/call-for-paper-724x1024.jpg\" alt=\"\" class=\"wp-image-22258\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/call-for-paper-724x1024.jpg 724w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/call-for-paper-212x300.jpg 212w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/call-for-paper-768x1086.jpg 768w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/call-for-paper.jpg 1076w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"738\" height=\"1024\" src=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/S__60997765-738x1024.jpg\" alt=\"\" class=\"wp-image-22259\" srcset=\"https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/S__60997765-738x1024.jpg 738w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/S__60997765-216x300.jpg 216w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/S__60997765-768x1065.jpg 768w, https:\/\/buulog.com\/wp-content\/uploads\/2025\/02\/S__60997765.jpg 1086w\" sizes=\"(max-width: 738px) 100vw, 738px\" \/><\/figure>\n\n\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \ud83d\udce3\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e48\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u2728\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e48\u0e32\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c (\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c)\u2728\u0e43\u0e19\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 19 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2569 \u0e13 \u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23 \u0e42\u0e14\u0e22 \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/buulog.com\/index.php\/wp-json\/wp\/v2\/pages\/22253"}],"collection":[{"href":"https:\/\/buulog.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/buulog.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/buulog.com\/index.php\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/buulog.com\/index.php\/wp-json\/wp\/v2\/comments?post=22253"}],"version-history":[{"count":40,"href":"https:\/\/buulog.com\/index.php\/wp-json\/wp\/v2\/pages\/22253\/revisions"}],"predecessor-version":[{"id":24681,"href":"https:\/\/buulog.com\/index.php\/wp-json\/wp\/v2\/pages\/22253\/revisions\/24681"}],"wp:attachment":[{"href":"https:\/\/buulog.com\/index.php\/wp-json\/wp\/v2\/media?parent=22253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}